{"id":272,"count":1,"description":"","link":"https:\/\/www.jftcomunicacion.es\/es\/category\/posicionamiento-web\/","name":"Posicionamiento web","slug":"posicionamiento-web","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Posicionamiento web archivos - Agencia de Publicidad JFT Comunicaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posicionamiento web archivos - Agencia de Publicidad JFT Comunicaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jftcomunicacion.es\/es\/category\/posicionamiento-web\/\" \/>\n<meta property=\"og:site_name\" content=\"Agencia de Publicidad JFT Comunicaci\u00f3n\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jftcomunicacion.es\/wp-content\/uploads\/2019\/12\/logo_jftcomunicacion-e1577624338378.png\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.jftcomunicacion.es\/es\/category\/posicionamiento-web\/\",\"url\":\"https:\/\/www.jftcomunicacion.es\/es\/category\/posicionamiento-web\/\",\"name\":\"Posicionamiento web archivos - Agencia de Publicidad JFT Comunicaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.jftcomunicacion.es\/es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.jftcomunicacion.es\/es\/category\/posicionamiento-web\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.jftcomunicacion.es\/es\/category\/posicionamiento-web\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.jftcomunicacion.es\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Posicionamiento web\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.jftcomunicacion.es\/es\/#website\",\"url\":\"https:\/\/www.jftcomunicacion.es\/es\/\",\"name\":\"JFT Comunicaci\u00f3n\",\"description\":\"Agencia de Publicidad y Marketing Digital\",\"publisher\":{\"@id\":\"https:\/\/www.jftcomunicacion.es\/es\/#organization\"},\"alternateName\":\"Agencia de Publicidad JFT Comunicaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.jftcomunicacion.es\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.jftcomunicacion.es\/es\/#organization\",\"name\":\"JFT Comunicaci\u00f3n\",\"alternateName\":\"Agencia de Publicidad en Canarias\",\"url\":\"https:\/\/www.jftcomunicacion.es\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.jftcomunicacion.es\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.jftcomunicacion.es\/wp-content\/uploads\/2019\/12\/logo_jftcomunicacion-e1577624338378.png\",\"contentUrl\":\"https:\/\/www.jftcomunicacion.es\/wp-content\/uploads\/2019\/12\/logo_jftcomunicacion-e1577624338378.png\",\"width\":280,\"height\":168,\"caption\":\"JFT Comunicaci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.jftcomunicacion.es\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/JFTComunicacion\",\"https:\/\/www.instagram.com\/jftcomunicacion\/\",\"https:\/\/www.linkedin.com\/company\/jft-comunicacin\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posicionamiento web archivos - Agencia de Publicidad JFT Comunicaci\u00f3n","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Posicionamiento web archivos - Agencia de Publicidad JFT Comunicaci\u00f3n","og_url":"https:\/\/www.jftcomunicacion.es\/es\/category\/posicionamiento-web\/","og_site_name":"Agencia de Publicidad JFT Comunicaci\u00f3n","og_image":[{"width":280,"height":168,"url":"https:\/\/www.jftcomunicacion.es\/wp-content\/uploads\/2019\/12\/logo_jftcomunicacion-e1577624338378.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.jftcomunicacion.es\/es\/category\/posicionamiento-web\/","url":"https:\/\/www.jftcomunicacion.es\/es\/category\/posicionamiento-web\/","name":"Posicionamiento web archivos - Agencia de Publicidad JFT Comunicaci\u00f3n","isPartOf":{"@id":"https:\/\/www.jftcomunicacion.es\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.jftcomunicacion.es\/es\/category\/posicionamiento-web\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jftcomunicacion.es\/es\/category\/posicionamiento-web\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.jftcomunicacion.es\/es\/"},{"@type":"ListItem","position":2,"name":"Posicionamiento web"}]},{"@type":"WebSite","@id":"https:\/\/www.jftcomunicacion.es\/es\/#website","url":"https:\/\/www.jftcomunicacion.es\/es\/","name":"JFT Comunicaci\u00f3n","description":"Agencia de Publicidad y Marketing Digital","publisher":{"@id":"https:\/\/www.jftcomunicacion.es\/es\/#organization"},"alternateName":"Agencia de Publicidad JFT Comunicaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jftcomunicacion.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.jftcomunicacion.es\/es\/#organization","name":"JFT Comunicaci\u00f3n","alternateName":"Agencia de Publicidad en Canarias","url":"https:\/\/www.jftcomunicacion.es\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.jftcomunicacion.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.jftcomunicacion.es\/wp-content\/uploads\/2019\/12\/logo_jftcomunicacion-e1577624338378.png","contentUrl":"https:\/\/www.jftcomunicacion.es\/wp-content\/uploads\/2019\/12\/logo_jftcomunicacion-e1577624338378.png","width":280,"height":168,"caption":"JFT Comunicaci\u00f3n"},"image":{"@id":"https:\/\/www.jftcomunicacion.es\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JFTComunicacion","https:\/\/www.instagram.com\/jftcomunicacion\/","https:\/\/www.linkedin.com\/company\/jft-comunicacin\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.jftcomunicacion.es\/es\/wp-json\/wp\/v2\/categories\/272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jftcomunicacion.es\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.jftcomunicacion.es\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.jftcomunicacion.es\/es\/wp-json\/wp\/v2\/posts?categories=272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}